{"id":10910,"date":"2023-03-13T11:11:56","date_gmt":"2023-03-13T11:11:56","guid":{"rendered":"https:\/\/targetmalaria.org\/press-release\/les-scientifiques-partagent-les-resultats-du-premier-lacher-de-moustiques-genetiquement-modifies-sans-impulsion-genetique-en-afrique\/"},"modified":"2026-06-23T17:18:35","modified_gmt":"2026-06-23T16:18:35","slug":"les-scientifiques-partagent-les-resultats-du-premier-lacher-de-moustiques-genetiquement-modifies-sans-impulsion-genetique-en-afrique","status":"publish","type":"press-release","link":"https:\/\/targetmalaria.org\/fr\/espace-presse-virtuel\/communiques-de-presse\/les-scientifiques-partagent-les-resultats-du-premier-lacher-de-moustiques-genetiquement-modifies-sans-impulsion-genetique-en-afrique\/","title":{"rendered":"Les scientifiques partagent les r\u00e9sultats du premier l\u00e2cher de moustiques g\u00e9n\u00e9tiquement modifi\u00e9s sans impulsion g\u00e9n\u00e9tique en Afrique"},"content":{"rendered":"<div class=\"press_release\">\t\n\t<div class=\"press_release_header\">\n\t\t\t<a class=\"download_press_release\" href=\"https:\/\/targetmalaria.org\/wp-content\/uploads\/2023\/03\/20220210_PR_FEPaperNatureComs_FRENCH.pdf\" target=\"_blank\"> Download PDF <i aria-hidden=\"true\" class=\"fas fa-file-download\"><\/i><\/a><h1>Les scientifiques partagent les r\u00e9sultats du premier l\u00e2cher de moustiques g\u00e9n\u00e9tiquement modifi\u00e9s sans impulsion g\u00e9n\u00e9tique en Afrique<\/h1>\t<\/div>\n<\/div>\n\n<p class=\"wp-block-paragraph\"><strong>Bobo-Dioulasso, Burkina Faso, 10 f\u00e9vrier 2022<\/strong> &#8211; L&rsquo;\u00e9quipe Target Malaria dirig\u00e9e par des scientifiques de l&rsquo;Institut de Recherche en Sciences de la Sant\u00e9 (IRSS) de Bobo-Dioulasso, Burkina Faso, pr\u00e9sente les r\u00e9sultats entomologiques du tout premier l\u00e2cher \u00e0 petite \u00e9chelle en Afrique de moustiques g\u00e9n\u00e9tiquement modifi\u00e9s en 2019 dans un nouvel article publi\u00e9 aujourd&rsquo;hui dans Nature Communications : \u201c<a href=\"https:\/\/www.nature.com\/articles\/s41467-022-28419-0\" target=\"_blank\" rel=\"noopener\">Mark-release-recapture experiment in Burkina Faso demonstrates reduced fitness and dispersal of genetically-modified sterile malaria mosquitoes<\/a>\u201d \u00ab Une exp\u00e9rience de marquage-l\u00e2cher-recapture au Burkina Faso d\u00e9montre une r\u00e9duction de la condition physique et de la dispersion des moustiques st\u00e9riles g\u00e9n\u00e9tiquement modifi\u00e9s porteurs du paludisme \u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c0 Bana, dans l&rsquo;ouest du Burkina Faso, des scientifiques ont suivi pendant plusieurs mois les d\u00e9placements et la survie de 14 850 moustiques m\u00e2les st\u00e9riles g\u00e9n\u00e9tiquement modifi\u00e9s et leurs fr\u00e8res non modifi\u00e9s qui ont \u00e9t\u00e9 l\u00e2ch\u00e9s le 1er juillet 2019.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab\u00a0Les objectifs de notre \u00e9tude \u00e9taient de d\u00e9montrer la capacit\u00e9 d&rsquo;estimer le taux de\nsurvie quotidien de la souche m\u00e2le st\u00e9rile de moustiques, d&rsquo;\u00e9valuer leur capacit\u00e9 \u00e0 participer \u00e0 des activit\u00e9s d&rsquo;essaimage critiques pour la reproduction, d&rsquo;\u00e9valuer leur dispersion dans la zone du l\u00e2cher et d&rsquo;estimer la taille de la population cible au moment du l\u00e2cher \u00bb, explique le Dr Franck A. Yao, Coordonnateur de l\u2019entomologie de terrain pour Target Malaria Burkina Faso.\n\nAu cours de la p\u00e9riode de 7 mois de l&rsquo;\u00e9tude, les chercheurs ont surveill\u00e9 le comportement et la zone de vol des moustiques. La premi\u00e8re d\u00e9couverte a \u00e9t\u00e9 que les moustiques l\u00e2ch\u00e9s ont particip\u00e9 aux activit\u00e9s d\u2019essaimage de la m\u00eame mani\u00e8re que leurs homologues sauvages. Comme pr\u00e9dit par les \u00e9tudes de laboratoire et de mod\u00e9lisation, apr\u00e8s les avoir captur\u00e9s, les chercheurs ont d\u00e9couvert que les moustiques g\u00e9n\u00e9tiquement modifi\u00e9s \u00e9taient moins mobiles que leurs fr\u00e8res non-transg\u00e9niques et avaient des taux de survie plus faibles. Le g\u00e8ne modifi\u00e9 a disparu de la population \u00e9tudi\u00e9e \u00e0 la fin du cycle de vie des m\u00e2les st\u00e9riles l\u00e2ch\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">The study gives scientists unique information about the fitness and behaviour of this non gene drive genetically modified strain of <em>Anopheles coluzzii <\/em>mosquitoes in a natural environment. Until the 2019 release in Burkina Faso, these non gene drive sterile male mosquitoes had only been studied in contained laboratory settings in Europe and Africa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&rsquo;\u00e9tude donne aux scientifiques des informations uniques sur la condition physique et le comportement de cette souche de moustiques Anopheles Coluzzii g\u00e9n\u00e9tiquement modifi\u00e9e sans impulsion g\u00e9n\u00e9tique dans un environnement naturel. Jusqu\u2019au l\u00e2cher de 2019, ces moustiques n&rsquo;avaient \u00e9t\u00e9 \u00e9tudi\u00e9s qu\u2019en milieu confin\u00e9 en Europe et en Afrique. Cette modification g\u00e9n\u00e9tique vise \u00e0 rendre les moustiques m\u00e2les st\u00e9riles. Ils peuvent s&rsquo;accoupler avec des femelles mais ne peuvent pas produire de prog\u00e9niture. La modification ne porte pas la technologie d\u2019impulsion g\u00e9n\u00e9tique.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&rsquo;\u00e9quipe de recherche travaille avec l\u2019esp\u00e8ce Anopheles Coluzzii car c&rsquo;est l&rsquo;une des 40 esp\u00e8ces de moustiques qui peuvent transmettre le paludisme \u00e0 l&rsquo;homme. C\u2019est le vecteur principal du paludisme au Burkina Faso. En 2020, les cas de paludisme et les d\u00e9c\u00e8s ont augment\u00e9 dans le monde, avec 241 millions de cas de paludisme et 627 000 d\u00e9c\u00e8s, 95 % des cas et 96 % des d\u00e9c\u00e8s survenant en Afrique (<a href=\"https:\/\/www.who.int\/teams\/global-malaria-programme\/reports\/world-malaria-report-2021\">Rapport mondial sur le paludisme 2021<\/a>).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les progr\u00e8s pour \u00e9liminer le paludisme en Afrique ont ralenti. Le Burkina Faso est l&rsquo;un des pays les plus touch\u00e9s par le paludisme au monde avec l&rsquo;ensemble de sa population de 21 millions d&rsquo;habitants \u00e0 risque, plus de 12 millions de cas et pr\u00e8s de 30 000 d\u00e9c\u00e8s par an (<a href=\"https:\/\/www.who.int\/teams\/global-malaria-programme\/reports\/world-malaria-report-2021\" target=\"_blank\" rel=\"noreferrer noopener\">Rapport mondial sur le paludisme 2021<\/a>).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Au cours des derni\u00e8res ann\u00e9es, il est devenu clair que les outils actuels de lutte contre le paludisme devront \u00eatre compl\u00e9t\u00e9s par de nouveaux outils, tels que les technologies g\u00e9n\u00e9tiques. Comme l&rsquo;indique la <a href=\"https:\/\/www.who.int\/news\/item\/14-10-2020-who-takes-a-position-on-genetically-modified-mosquitoes\" target=\"_blank\" rel=\"noopener\">d\u00e9claration de l\u2019OMS<\/a> publi\u00e9e en octobre 2020 : \u00ab Reconnaissant le besoin urgent de nouveaux outils pour lutter contre les maladies \u00e0 transmission vectorielle et dans l&rsquo;esprit de favoriser l&rsquo;innovation, l&rsquo;OMS soutient l&rsquo;\u00e9tude de toutes les technologies potentiellement b\u00e9n\u00e9fiques, y compris les moustiques\ng\u00e9n\u00e9tiquement modifi\u00e9s \u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les scientifiques de l&rsquo;IRSS, qui ont dirig\u00e9 le l\u00e2cher, font partie du consortium international \u00e0 but non lucratif, Target Malaria, dont l&rsquo;objectif est d&rsquo;utiliser des technologies g\u00e9n\u00e9tiques pour r\u00e9duire la population de moustiques transmettant le paludisme en Afrique subsaharienne.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab Bien que l\u2019objectif du l\u00e2cher \u00e0 petite \u00e9chelle n\u2019\u00e9tait pas d\u2019\u00eatre un outil de lutte contre le paludisme, il s&rsquo;agissait d&rsquo;une \u00e9tape importante pour l&rsquo;\u00e9quipe afin de <a href=\"https:\/\/targetmalaria.org\/fr\/results-from-months-of-monitoring-following-the-first-release-of-non-gene-drive-genetically-modified-mosquitoes-in-africa\/\">recueillir des informations, d&rsquo;acqu\u00e9rir des connaissances et de d\u00e9velopper des comp\u00e9tences locales<\/a>. Les donn\u00e9es scientifiques que nous avons obtenues seront essentielles dans le d\u00e9veloppement de nos prochaines phases de recherche \u00bb, a d\u00e9clar\u00e9 le professeur Abdoulaye Diabat\u00e9, chercheur principal de Target Malaria Burkina Faso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&rsquo;\u00e9tude a \u00e9galement permis \u00e0 l&rsquo;\u00e9quipe de travailler en \u00e9troite collaboration avec les communaut\u00e9s affect\u00e9es et les autorit\u00e9s r\u00e9glementaires et d\u2019engager un dialogue continu avec ces parties prenantes sur les approches g\u00e9n\u00e9tiques de la lutte contre le paludisme.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab Le l\u00e2cher de Target Malaria est une \u00e9tape cruciale vers le d\u00e9veloppement de nouveaux outils exploitant la puissance de l&rsquo;\u00e9dition g\u00e9n\u00e9tique pr\u00e9cise en vue de l&rsquo;\u00e9limination future du paludisme. Les donn\u00e9es recueillies dans le cadre de cette \u00e9tude permettront de d\u00e9velopper de nouvelles souches avec une meilleure survie et une efficacit\u00e9 accrue. C&rsquo;est un nouveau chapitre important dans la lutte contre le paludisme \u00bb, a not\u00e9 le professeur Fr\u00e9d\u00e9ric Tripet, chercheur principal en entomologie pour Target Malaria, Universit\u00e9 de Keele.<\/p>\n","protected":false},"featured_media":13070,"template":"","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","featured_image_focal_point":[],"footnotes":""},"profile_tax":[651],"class_list":["post-10910","press-release","type-press-release","status-publish","has-post-thumbnail","hentry","press_release_cat-press-release","country-burkina-faso"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les scientifiques partagent les r\u00e9sultats du premier l\u00e2cher de moustiques g\u00e9n\u00e9tiquement modifi\u00e9s sans impulsion g\u00e9n\u00e9tique en Afrique - Target Malaria<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/targetmalaria.org\/fr\/espace-presse-virtuel\/communiques-de-presse\/les-scientifiques-partagent-les-resultats-du-premier-lacher-de-moustiques-genetiquement-modifies-sans-impulsion-genetique-en-afrique\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les scientifiques partagent les r\u00e9sultats du premier l\u00e2cher de moustiques g\u00e9n\u00e9tiquement modifi\u00e9s sans impulsion g\u00e9n\u00e9tique en Afrique - Target Malaria\" \/>\n<meta property=\"og:description\" content=\"Bobo-Dioulasso, Burkina Faso, 10 f\u00e9vrier 2022 &#8211; L&rsquo;\u00e9quipe Target Malaria dirig\u00e9e par des scientifiques de l&rsquo;Institut de Recherche en Sciences de la Sant\u00e9 (IRSS) de Bobo-Dioulasso, Burkina Faso, pr\u00e9sente les r\u00e9sultats entomologiques du tout premier l\u00e2cher \u00e0 petite \u00e9chelle en Afrique de moustiques g\u00e9n\u00e9tiquement modifi\u00e9s en 2019 dans un nouvel article publi\u00e9 aujourd&rsquo;hui dans Nature [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/targetmalaria.org\/fr\/espace-presse-virtuel\/communiques-de-presse\/les-scientifiques-partagent-les-resultats-du-premier-lacher-de-moustiques-genetiquement-modifies-sans-impulsion-genetique-en-afrique\/\" \/>\n<meta property=\"og:site_name\" content=\"Target Malaria\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TargetMalariaGlobal\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-23T16:18:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/targetmalaria.org\/wp-content\/uploads\/2023\/06\/0c402133-ff67-41bc-9670-37e5efaf06a0_alta-libre-aspect-ratio_default_0_x1332y86.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@TargetMalaria\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/espace-presse-virtuel\\\/communiques-de-presse\\\/les-scientifiques-partagent-les-resultats-du-premier-lacher-de-moustiques-genetiquement-modifies-sans-impulsion-genetique-en-afrique\\\/\",\"url\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/espace-presse-virtuel\\\/communiques-de-presse\\\/les-scientifiques-partagent-les-resultats-du-premier-lacher-de-moustiques-genetiquement-modifies-sans-impulsion-genetique-en-afrique\\\/\",\"name\":\"Les scientifiques partagent les r\u00e9sultats du premier l\u00e2cher de moustiques g\u00e9n\u00e9tiquement modifi\u00e9s sans impulsion g\u00e9n\u00e9tique en Afrique - Target Malaria\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/espace-presse-virtuel\\\/communiques-de-presse\\\/les-scientifiques-partagent-les-resultats-du-premier-lacher-de-moustiques-genetiquement-modifies-sans-impulsion-genetique-en-afrique\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/espace-presse-virtuel\\\/communiques-de-presse\\\/les-scientifiques-partagent-les-resultats-du-premier-lacher-de-moustiques-genetiquement-modifies-sans-impulsion-genetique-en-afrique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/targetmalaria.org\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/0c402133-ff67-41bc-9670-37e5efaf06a0_alta-libre-aspect-ratio_default_0_x1332y86.jpg\",\"datePublished\":\"2023-03-13T11:11:56+00:00\",\"dateModified\":\"2026-06-23T16:18:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/espace-presse-virtuel\\\/communiques-de-presse\\\/les-scientifiques-partagent-les-resultats-du-premier-lacher-de-moustiques-genetiquement-modifies-sans-impulsion-genetique-en-afrique\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/espace-presse-virtuel\\\/communiques-de-presse\\\/les-scientifiques-partagent-les-resultats-du-premier-lacher-de-moustiques-genetiquement-modifies-sans-impulsion-genetique-en-afrique\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/espace-presse-virtuel\\\/communiques-de-presse\\\/les-scientifiques-partagent-les-resultats-du-premier-lacher-de-moustiques-genetiquement-modifies-sans-impulsion-genetique-en-afrique\\\/#primaryimage\",\"url\":\"https:\\\/\\\/targetmalaria.org\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/0c402133-ff67-41bc-9670-37e5efaf06a0_alta-libre-aspect-ratio_default_0_x1332y86.jpg\",\"contentUrl\":\"https:\\\/\\\/targetmalaria.org\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/0c402133-ff67-41bc-9670-37e5efaf06a0_alta-libre-aspect-ratio_default_0_x1332y86.jpg\",\"width\":\"1200\",\"height\":\"800\",\"caption\":\"Swarming\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/espace-presse-virtuel\\\/communiques-de-presse\\\/les-scientifiques-partagent-les-resultats-du-premier-lacher-de-moustiques-genetiquement-modifies-sans-impulsion-genetique-en-afrique\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les scientifiques partagent les r\u00e9sultats du premier l\u00e2cher de moustiques g\u00e9n\u00e9tiquement modifi\u00e9s sans impulsion g\u00e9n\u00e9tique en Afrique\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/\",\"name\":\"Target Malaria\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/#organization\",\"name\":\"Target Malaria\",\"url\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/targetmalaria.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/target_malaria_bf_logo.png\",\"contentUrl\":\"https:\\\/\\\/targetmalaria.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/target_malaria_bf_logo.png\",\"width\":1920,\"height\":1080,\"caption\":\"Target Malaria\"},\"image\":{\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/TargetMalariaGlobal\\\/\",\"https:\\\/\\\/x.com\\\/TargetMalaria\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/target-malaria\",\"https:\\\/\\\/youtube.com\\\/@TargetMalaria\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les scientifiques partagent les r\u00e9sultats du premier l\u00e2cher de moustiques g\u00e9n\u00e9tiquement modifi\u00e9s sans impulsion g\u00e9n\u00e9tique en Afrique - Target Malaria","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/targetmalaria.org\/fr\/espace-presse-virtuel\/communiques-de-presse\/les-scientifiques-partagent-les-resultats-du-premier-lacher-de-moustiques-genetiquement-modifies-sans-impulsion-genetique-en-afrique\/","og_locale":"fr_FR","og_type":"article","og_title":"Les scientifiques partagent les r\u00e9sultats du premier l\u00e2cher de moustiques g\u00e9n\u00e9tiquement modifi\u00e9s sans impulsion g\u00e9n\u00e9tique en Afrique - Target Malaria","og_description":"Bobo-Dioulasso, Burkina Faso, 10 f\u00e9vrier 2022 &#8211; L&rsquo;\u00e9quipe Target Malaria dirig\u00e9e par des scientifiques de l&rsquo;Institut de Recherche en Sciences de la Sant\u00e9 (IRSS) de Bobo-Dioulasso, Burkina Faso, pr\u00e9sente les r\u00e9sultats entomologiques du tout premier l\u00e2cher \u00e0 petite \u00e9chelle en Afrique de moustiques g\u00e9n\u00e9tiquement modifi\u00e9s en 2019 dans un nouvel article publi\u00e9 aujourd&rsquo;hui dans Nature [&hellip;]","og_url":"https:\/\/targetmalaria.org\/fr\/espace-presse-virtuel\/communiques-de-presse\/les-scientifiques-partagent-les-resultats-du-premier-lacher-de-moustiques-genetiquement-modifies-sans-impulsion-genetique-en-afrique\/","og_site_name":"Target Malaria","article_publisher":"https:\/\/www.facebook.com\/TargetMalariaGlobal\/","article_modified_time":"2026-06-23T16:18:35+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/targetmalaria.org\/wp-content\/uploads\/2023\/06\/0c402133-ff67-41bc-9670-37e5efaf06a0_alta-libre-aspect-ratio_default_0_x1332y86.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@TargetMalaria","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ItemPage"],"@id":"https:\/\/targetmalaria.org\/fr\/espace-presse-virtuel\/communiques-de-presse\/les-scientifiques-partagent-les-resultats-du-premier-lacher-de-moustiques-genetiquement-modifies-sans-impulsion-genetique-en-afrique\/","url":"https:\/\/targetmalaria.org\/fr\/espace-presse-virtuel\/communiques-de-presse\/les-scientifiques-partagent-les-resultats-du-premier-lacher-de-moustiques-genetiquement-modifies-sans-impulsion-genetique-en-afrique\/","name":"Les scientifiques partagent les r\u00e9sultats du premier l\u00e2cher de moustiques g\u00e9n\u00e9tiquement modifi\u00e9s sans impulsion g\u00e9n\u00e9tique en Afrique - Target Malaria","isPartOf":{"@id":"https:\/\/targetmalaria.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/targetmalaria.org\/fr\/espace-presse-virtuel\/communiques-de-presse\/les-scientifiques-partagent-les-resultats-du-premier-lacher-de-moustiques-genetiquement-modifies-sans-impulsion-genetique-en-afrique\/#primaryimage"},"image":{"@id":"https:\/\/targetmalaria.org\/fr\/espace-presse-virtuel\/communiques-de-presse\/les-scientifiques-partagent-les-resultats-du-premier-lacher-de-moustiques-genetiquement-modifies-sans-impulsion-genetique-en-afrique\/#primaryimage"},"thumbnailUrl":"https:\/\/targetmalaria.org\/wp-content\/uploads\/2023\/06\/0c402133-ff67-41bc-9670-37e5efaf06a0_alta-libre-aspect-ratio_default_0_x1332y86.jpg","datePublished":"2023-03-13T11:11:56+00:00","dateModified":"2026-06-23T16:18:35+00:00","breadcrumb":{"@id":"https:\/\/targetmalaria.org\/fr\/espace-presse-virtuel\/communiques-de-presse\/les-scientifiques-partagent-les-resultats-du-premier-lacher-de-moustiques-genetiquement-modifies-sans-impulsion-genetique-en-afrique\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/targetmalaria.org\/fr\/espace-presse-virtuel\/communiques-de-presse\/les-scientifiques-partagent-les-resultats-du-premier-lacher-de-moustiques-genetiquement-modifies-sans-impulsion-genetique-en-afrique\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/targetmalaria.org\/fr\/espace-presse-virtuel\/communiques-de-presse\/les-scientifiques-partagent-les-resultats-du-premier-lacher-de-moustiques-genetiquement-modifies-sans-impulsion-genetique-en-afrique\/#primaryimage","url":"https:\/\/targetmalaria.org\/wp-content\/uploads\/2023\/06\/0c402133-ff67-41bc-9670-37e5efaf06a0_alta-libre-aspect-ratio_default_0_x1332y86.jpg","contentUrl":"https:\/\/targetmalaria.org\/wp-content\/uploads\/2023\/06\/0c402133-ff67-41bc-9670-37e5efaf06a0_alta-libre-aspect-ratio_default_0_x1332y86.jpg","width":"1200","height":"800","caption":"Swarming"},{"@type":"BreadcrumbList","@id":"https:\/\/targetmalaria.org\/fr\/espace-presse-virtuel\/communiques-de-presse\/les-scientifiques-partagent-les-resultats-du-premier-lacher-de-moustiques-genetiquement-modifies-sans-impulsion-genetique-en-afrique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/targetmalaria.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Les scientifiques partagent les r\u00e9sultats du premier l\u00e2cher de moustiques g\u00e9n\u00e9tiquement modifi\u00e9s sans impulsion g\u00e9n\u00e9tique en Afrique"}]},{"@type":"WebSite","@id":"https:\/\/targetmalaria.org\/fr\/#website","url":"https:\/\/targetmalaria.org\/fr\/","name":"Target Malaria","description":"","publisher":{"@id":"https:\/\/targetmalaria.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/targetmalaria.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/targetmalaria.org\/fr\/#organization","name":"Target Malaria","url":"https:\/\/targetmalaria.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/targetmalaria.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/targetmalaria.org\/wp-content\/uploads\/2025\/08\/target_malaria_bf_logo.png","contentUrl":"https:\/\/targetmalaria.org\/wp-content\/uploads\/2025\/08\/target_malaria_bf_logo.png","width":1920,"height":1080,"caption":"Target Malaria"},"image":{"@id":"https:\/\/targetmalaria.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/TargetMalariaGlobal\/","https:\/\/x.com\/TargetMalaria","https:\/\/www.linkedin.com\/company\/target-malaria","https:\/\/youtube.com\/@TargetMalaria"]}]}},"_links":{"self":[{"href":"https:\/\/targetmalaria.org\/fr\/wp-json\/wp\/v2\/press-release\/10910","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/targetmalaria.org\/fr\/wp-json\/wp\/v2\/press-release"}],"about":[{"href":"https:\/\/targetmalaria.org\/fr\/wp-json\/wp\/v2\/types\/press-release"}],"version-history":[{"count":0,"href":"https:\/\/targetmalaria.org\/fr\/wp-json\/wp\/v2\/press-release\/10910\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/targetmalaria.org\/fr\/wp-json\/wp\/v2\/media\/13070"}],"wp:attachment":[{"href":"https:\/\/targetmalaria.org\/fr\/wp-json\/wp\/v2\/media?parent=10910"}],"wp:term":[{"taxonomy":"profile_tax","embeddable":true,"href":"https:\/\/targetmalaria.org\/fr\/wp-json\/wp\/v2\/profile_tax?post=10910"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}