{"id":7098,"date":"2022-01-25T14:24:00","date_gmt":"2022-01-25T14:24:00","guid":{"rendered":"https:\/\/targetmalaria.org\/?p=7098"},"modified":"2023-11-06T13:29:52","modified_gmt":"2023-11-06T13:29:52","slug":"nouvel-immeuble-de-bureaux-pour-lequipe-de-target-malaria-mali","status":"publish","type":"post","link":"https:\/\/targetmalaria.org\/fr\/latest\/actus\/nouvel-immeuble-de-bureaux-pour-lequipe-de-target-malaria-mali\/","title":{"rendered":"Nouvel immeuble de bureaux pour l\u2019\u00e9quipe de Target Malaria Mali"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Nouvel An, nouveau bureau ! Nous sommes ravis que la construction du bureau de l\u2019\u00e9quipe de Target Malaria Mali soit maintenant achev\u00e9e.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bas\u00e9 au c\u0153ur du Malaria Research and Training Centre (MRTC) de l\u2019universit\u00e9 des sciences, des techniques et de la technologie de Bamako, le nouveau bureau est situ\u00e9 derri\u00e8re la biblioth\u00e8que de la facult\u00e9 de m\u00e9decine et de pharmacie.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Target Malaria travaille en partenariat avec le MRTC depuis 2012, et ce nouveau bureau repr\u00e9sente les liens \u00e9troits entre l\u2019institution et l\u2019\u00e9quipe de Target Malaria, contribuant \u00e0 fournir un meilleur environnement de travail encourageant la coh\u00e9sion.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/targetmalaria.org\/wp-content\/uploads\/2022\/01\/image-15.png\" alt=\"\" class=\"wp-image-6814\" width=\"660\" height=\"270\" srcset=\"https:\/\/targetmalaria.org\/wp-content\/uploads\/2022\/01\/image-15.png 962w, https:\/\/targetmalaria.org\/wp-content\/uploads\/2022\/01\/image-15-300x123.png 300w, https:\/\/targetmalaria.org\/wp-content\/uploads\/2022\/01\/image-15-768x315.png 768w\" sizes=\"auto, (max-width: 660px) 100vw, 660px\" \/><figcaption><em><sup>Nouvel immeuble de bureaux au Mali \u00e0 l\u2019universit\u00e9 des sciences, des techniques et de la technologie de Bamako<\/sup><\/em><\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Le nouveau b\u00e2timent regroupe toute l\u2019\u00e9quipe de Target Malaria Mali sous un m\u00eame toit, et offre suffisamment d\u2019espace pour que les \u00e9quipes disposent de leurs propres bureaux<\/strong>. Le b\u00e2timent comprend une salle de conf\u00e9rence pouvant accueillir jusqu\u2019\u00e0 50 personnes, une salle de r\u00e9union pouvant accueillir jusqu\u2019\u00e0 10 personnes et des espaces de bureau pour les \u00e9quipes individuelles. Les \u00e9quipes d\u2019entomologie, de l\u2019insectarium, d\u2019engagement des parties prenantes et de communication disposent toutes d\u2019espaces de travail pouvant accueillir jusqu\u2019\u00e0 six personnes. Le chercheur principal et la direction ont \u00e9galement un bureau privatif.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>2021 a \u00e9t\u00e9 une ann\u00e9e passionnante pour Target Malaria Mali<\/strong>, car nous avons <a href=\"https:\/\/targetmalaria.org\/two-years-of-laboratory-studies-on-the-non-gene-drive-genetically-modified-sterile-male-mosquitoes-concluded-successfully-in-mali\/\">conclu deux ann\u00e9es d\u2019\u00e9tudes en milieu confin\u00e9<\/a> sur les moustiques m\u00e2les st\u00e9riles g\u00e9n\u00e9tiquement modifi\u00e9s \u00e0 impulsion non g\u00e9n\u00e9tique log\u00e9s dans notre <a href=\"https:\/\/vimeo.com\/281267030\">insectarium ACL-2<\/a>. Avec un nouvel espace de bureau pour 2022 et des travaux passionnants en cours, j\u2019ai h\u00e2te de voir tout ce que cette ann\u00e9e apportera \u00e0 notre \u00e9quipe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Au nom de toute l\u2019\u00e9quipe de Target Malaria Mali, je tiens \u00e0 remercier tous ceux qui ont contribu\u00e9 \u00e0 la r\u00e9alisation de ce nouveau bureau, marquant un nouveau chapitre passionnant pour l\u2019\u00e9quipe malienne.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nouvel An, nouveau bureau ! Nous sommes ravis que la construction du bureau de l\u2019\u00e9quipe de Target Malaria Mali soit maintenant achev\u00e9e. Bas\u00e9 au c\u0153ur du Malaria Research and Training Centre (MRTC) de l\u2019universit\u00e9 des sciences, des techniques et de la technologie de Bamako, le nouveau bureau est situ\u00e9 derri\u00e8re la biblioth\u00e8que de la facult\u00e9 [&hellip;]<\/p>\n","protected":false},"author":32,"featured_media":6814,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","featured_image_focal_point":[],"_image_focal_point":[],"footnotes":""},"categories":[88],"profile_tax":[],"class_list":["post-7098","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actus","country-mali","post_writers-mamadou-coulibaly","post_writers-mamadou-coulibaly-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nouvel immeuble de bureaux pour l\u2019\u00e9quipe de Target Malaria Mali - Target Malaria<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/targetmalaria.org\/fr\/latest\/actus\/nouvel-immeuble-de-bureaux-pour-lequipe-de-target-malaria-mali\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nouvel immeuble de bureaux pour l\u2019\u00e9quipe de Target Malaria Mali - Target Malaria\" \/>\n<meta property=\"og:description\" content=\"Nouvel An, nouveau bureau ! Nous sommes ravis que la construction du bureau de l\u2019\u00e9quipe de Target Malaria Mali soit maintenant achev\u00e9e. Bas\u00e9 au c\u0153ur du Malaria Research and Training Centre (MRTC) de l\u2019universit\u00e9 des sciences, des techniques et de la technologie de Bamako, le nouveau bureau est situ\u00e9 derri\u00e8re la biblioth\u00e8que de la facult\u00e9 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/targetmalaria.org\/fr\/latest\/actus\/nouvel-immeuble-de-bureaux-pour-lequipe-de-target-malaria-mali\/\" \/>\n<meta property=\"og:site_name\" content=\"Target Malaria\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TargetMalariaGlobal\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-25T14:24:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-06T13:29:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/targetmalaria.org\/wp-content\/uploads\/2022\/01\/image-15.png\" \/>\n\t<meta property=\"og:image:width\" content=\"962\" \/>\n\t<meta property=\"og:image:height\" content=\"394\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Yann Pablo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@TargetMalaria\" \/>\n<meta name=\"twitter:site\" content=\"@TargetMalaria\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Yann Pablo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/latest\\\/actus\\\/nouvel-immeuble-de-bureaux-pour-lequipe-de-target-malaria-mali\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/latest\\\/actus\\\/nouvel-immeuble-de-bureaux-pour-lequipe-de-target-malaria-mali\\\/\"},\"author\":{\"name\":\"Yann Pablo\",\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/#\\\/schema\\\/person\\\/c4715c8d1e550240ac403f56f435e8c8\"},\"headline\":\"Nouvel immeuble de bureaux pour l\u2019\u00e9quipe de Target Malaria Mali\",\"datePublished\":\"2022-01-25T14:24:00+00:00\",\"dateModified\":\"2023-11-06T13:29:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/latest\\\/actus\\\/nouvel-immeuble-de-bureaux-pour-lequipe-de-target-malaria-mali\\\/\"},\"wordCount\":339,\"publisher\":{\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/latest\\\/actus\\\/nouvel-immeuble-de-bureaux-pour-lequipe-de-target-malaria-mali\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/targetmalaria.org\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/image-15.png\",\"articleSection\":[\"Actus\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/latest\\\/actus\\\/nouvel-immeuble-de-bureaux-pour-lequipe-de-target-malaria-mali\\\/\",\"url\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/latest\\\/actus\\\/nouvel-immeuble-de-bureaux-pour-lequipe-de-target-malaria-mali\\\/\",\"name\":\"Nouvel immeuble de bureaux pour l\u2019\u00e9quipe de Target Malaria Mali - Target Malaria\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/latest\\\/actus\\\/nouvel-immeuble-de-bureaux-pour-lequipe-de-target-malaria-mali\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/latest\\\/actus\\\/nouvel-immeuble-de-bureaux-pour-lequipe-de-target-malaria-mali\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/targetmalaria.org\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/image-15.png\",\"datePublished\":\"2022-01-25T14:24:00+00:00\",\"dateModified\":\"2023-11-06T13:29:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/latest\\\/actus\\\/nouvel-immeuble-de-bureaux-pour-lequipe-de-target-malaria-mali\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/latest\\\/actus\\\/nouvel-immeuble-de-bureaux-pour-lequipe-de-target-malaria-mali\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/latest\\\/actus\\\/nouvel-immeuble-de-bureaux-pour-lequipe-de-target-malaria-mali\\\/#primaryimage\",\"url\":\"https:\\\/\\\/targetmalaria.org\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/image-15.png\",\"contentUrl\":\"https:\\\/\\\/targetmalaria.org\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/image-15.png\",\"width\":962,\"height\":394},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/latest\\\/actus\\\/nouvel-immeuble-de-bureaux-pour-lequipe-de-target-malaria-mali\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nouvel immeuble de bureaux pour l\u2019\u00e9quipe de Target Malaria Mali\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/\",\"name\":\"Target Malaria\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/#organization\",\"name\":\"Target Malaria\",\"url\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/targetmalaria.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/target_malaria_bf_logo.png\",\"contentUrl\":\"https:\\\/\\\/targetmalaria.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/target_malaria_bf_logo.png\",\"width\":1920,\"height\":1080,\"caption\":\"Target Malaria\"},\"image\":{\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/TargetMalariaGlobal\\\/\",\"https:\\\/\\\/x.com\\\/TargetMalaria\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/target-malaria\",\"https:\\\/\\\/youtube.com\\\/@TargetMalaria\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/#\\\/schema\\\/person\\\/c4715c8d1e550240ac403f56f435e8c8\",\"name\":\"Yann Pablo\",\"sameAs\":[\"https:\\\/\\\/whybe.ch\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nouvel immeuble de bureaux pour l\u2019\u00e9quipe de Target Malaria Mali - Target Malaria","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/targetmalaria.org\/fr\/latest\/actus\/nouvel-immeuble-de-bureaux-pour-lequipe-de-target-malaria-mali\/","og_locale":"fr_FR","og_type":"article","og_title":"Nouvel immeuble de bureaux pour l\u2019\u00e9quipe de Target Malaria Mali - Target Malaria","og_description":"Nouvel An, nouveau bureau ! Nous sommes ravis que la construction du bureau de l\u2019\u00e9quipe de Target Malaria Mali soit maintenant achev\u00e9e. Bas\u00e9 au c\u0153ur du Malaria Research and Training Centre (MRTC) de l\u2019universit\u00e9 des sciences, des techniques et de la technologie de Bamako, le nouveau bureau est situ\u00e9 derri\u00e8re la biblioth\u00e8que de la facult\u00e9 [&hellip;]","og_url":"https:\/\/targetmalaria.org\/fr\/latest\/actus\/nouvel-immeuble-de-bureaux-pour-lequipe-de-target-malaria-mali\/","og_site_name":"Target Malaria","article_publisher":"https:\/\/www.facebook.com\/TargetMalariaGlobal\/","article_published_time":"2022-01-25T14:24:00+00:00","article_modified_time":"2023-11-06T13:29:52+00:00","og_image":[{"width":962,"height":394,"url":"https:\/\/targetmalaria.org\/wp-content\/uploads\/2022\/01\/image-15.png","type":"image\/png"}],"author":"Yann Pablo","twitter_card":"summary_large_image","twitter_creator":"@TargetMalaria","twitter_site":"@TargetMalaria","twitter_misc":{"\u00c9crit par":"Yann Pablo","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/targetmalaria.org\/fr\/latest\/actus\/nouvel-immeuble-de-bureaux-pour-lequipe-de-target-malaria-mali\/#article","isPartOf":{"@id":"https:\/\/targetmalaria.org\/fr\/latest\/actus\/nouvel-immeuble-de-bureaux-pour-lequipe-de-target-malaria-mali\/"},"author":{"name":"Yann Pablo","@id":"https:\/\/targetmalaria.org\/fr\/#\/schema\/person\/c4715c8d1e550240ac403f56f435e8c8"},"headline":"Nouvel immeuble de bureaux pour l\u2019\u00e9quipe de Target Malaria Mali","datePublished":"2022-01-25T14:24:00+00:00","dateModified":"2023-11-06T13:29:52+00:00","mainEntityOfPage":{"@id":"https:\/\/targetmalaria.org\/fr\/latest\/actus\/nouvel-immeuble-de-bureaux-pour-lequipe-de-target-malaria-mali\/"},"wordCount":339,"publisher":{"@id":"https:\/\/targetmalaria.org\/fr\/#organization"},"image":{"@id":"https:\/\/targetmalaria.org\/fr\/latest\/actus\/nouvel-immeuble-de-bureaux-pour-lequipe-de-target-malaria-mali\/#primaryimage"},"thumbnailUrl":"https:\/\/targetmalaria.org\/wp-content\/uploads\/2022\/01\/image-15.png","articleSection":["Actus"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/targetmalaria.org\/fr\/latest\/actus\/nouvel-immeuble-de-bureaux-pour-lequipe-de-target-malaria-mali\/","url":"https:\/\/targetmalaria.org\/fr\/latest\/actus\/nouvel-immeuble-de-bureaux-pour-lequipe-de-target-malaria-mali\/","name":"Nouvel immeuble de bureaux pour l\u2019\u00e9quipe de Target Malaria Mali - Target Malaria","isPartOf":{"@id":"https:\/\/targetmalaria.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/targetmalaria.org\/fr\/latest\/actus\/nouvel-immeuble-de-bureaux-pour-lequipe-de-target-malaria-mali\/#primaryimage"},"image":{"@id":"https:\/\/targetmalaria.org\/fr\/latest\/actus\/nouvel-immeuble-de-bureaux-pour-lequipe-de-target-malaria-mali\/#primaryimage"},"thumbnailUrl":"https:\/\/targetmalaria.org\/wp-content\/uploads\/2022\/01\/image-15.png","datePublished":"2022-01-25T14:24:00+00:00","dateModified":"2023-11-06T13:29:52+00:00","breadcrumb":{"@id":"https:\/\/targetmalaria.org\/fr\/latest\/actus\/nouvel-immeuble-de-bureaux-pour-lequipe-de-target-malaria-mali\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/targetmalaria.org\/fr\/latest\/actus\/nouvel-immeuble-de-bureaux-pour-lequipe-de-target-malaria-mali\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/targetmalaria.org\/fr\/latest\/actus\/nouvel-immeuble-de-bureaux-pour-lequipe-de-target-malaria-mali\/#primaryimage","url":"https:\/\/targetmalaria.org\/wp-content\/uploads\/2022\/01\/image-15.png","contentUrl":"https:\/\/targetmalaria.org\/wp-content\/uploads\/2022\/01\/image-15.png","width":962,"height":394},{"@type":"BreadcrumbList","@id":"https:\/\/targetmalaria.org\/fr\/latest\/actus\/nouvel-immeuble-de-bureaux-pour-lequipe-de-target-malaria-mali\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/targetmalaria.org\/fr\/"},{"@type":"ListItem","position":2,"name":"Nouvel immeuble de bureaux pour l\u2019\u00e9quipe de Target Malaria Mali"}]},{"@type":"WebSite","@id":"https:\/\/targetmalaria.org\/fr\/#website","url":"https:\/\/targetmalaria.org\/fr\/","name":"Target Malaria","description":"","publisher":{"@id":"https:\/\/targetmalaria.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/targetmalaria.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/targetmalaria.org\/fr\/#organization","name":"Target Malaria","url":"https:\/\/targetmalaria.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/targetmalaria.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/targetmalaria.org\/wp-content\/uploads\/2025\/08\/target_malaria_bf_logo.png","contentUrl":"https:\/\/targetmalaria.org\/wp-content\/uploads\/2025\/08\/target_malaria_bf_logo.png","width":1920,"height":1080,"caption":"Target Malaria"},"image":{"@id":"https:\/\/targetmalaria.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/TargetMalariaGlobal\/","https:\/\/x.com\/TargetMalaria","https:\/\/www.linkedin.com\/company\/target-malaria","https:\/\/youtube.com\/@TargetMalaria"]},{"@type":"Person","@id":"https:\/\/targetmalaria.org\/fr\/#\/schema\/person\/c4715c8d1e550240ac403f56f435e8c8","name":"Yann Pablo","sameAs":["https:\/\/whybe.ch"]}]}},"_links":{"self":[{"href":"https:\/\/targetmalaria.org\/fr\/wp-json\/wp\/v2\/posts\/7098","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/targetmalaria.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/targetmalaria.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/targetmalaria.org\/fr\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/targetmalaria.org\/fr\/wp-json\/wp\/v2\/comments?post=7098"}],"version-history":[{"count":0,"href":"https:\/\/targetmalaria.org\/fr\/wp-json\/wp\/v2\/posts\/7098\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/targetmalaria.org\/fr\/wp-json\/wp\/v2\/media\/6814"}],"wp:attachment":[{"href":"https:\/\/targetmalaria.org\/fr\/wp-json\/wp\/v2\/media?parent=7098"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/targetmalaria.org\/fr\/wp-json\/wp\/v2\/categories?post=7098"},{"taxonomy":"profile_tax","embeddable":true,"href":"https:\/\/targetmalaria.org\/fr\/wp-json\/wp\/v2\/profile_tax?post=7098"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}