{"id":6949,"date":"2021-04-07T10:20:00","date_gmt":"2021-04-07T09:20:00","guid":{"rendered":"https:\/\/targetmalaria.org\/?p=6949"},"modified":"2025-08-29T08:36:45","modified_gmt":"2025-08-29T07:36:45","slug":"celebration-de-la-journee-mondiale-de-la-sante","status":"publish","type":"post","link":"https:\/\/targetmalaria.org\/fr\/latest\/actus\/celebration-de-la-journee-mondiale-de-la-sante\/","title":{"rendered":"C\u00e9l\u00e9bration de la Journ\u00e9e mondiale de la Sant\u00e9"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Le 7 avril, nous c\u00e9l\u00e9brons la Journ\u00e9e mondiale de la Sant\u00e9. Depuis 50 ans, cette journ\u00e9e a mis en lumi\u00e8re des questions importantes telles que la sant\u00e9 mentale, le r\u00f4le des infirmiers, infirmi\u00e8res et sages-femmes et l\u2019importance de la couverture sant\u00e9 universelle. Cette ann\u00e9e, la \u00ab&nbsp;<strong>Construction d\u2019un monde plus \u00e9quitable, plus sain<\/strong>&nbsp;\u00bb est le th\u00e8me choisi pour cette journ\u00e9e. Comme la pand\u00e9mie de COVID-19 l\u2019a montr\u00e9, les disparit\u00e9s sont trop importantes entre ceux qui peuvent vivre en bonne sant\u00e9 et acc\u00e9der aux soins et les autres qui ne le peuvent pas. C\u2019est enti\u00e8rement d\u00e9pendant de la situation dans laquelle les enfants viennent au monde, grandissent, l\u2019endroit o\u00f9 ils vivent et dans quelles conditions ils travaillent une fois arriv\u00e9s \u00e0 l\u2019\u00e2ge adulte. En cette <a href=\"https:\/\/www.who.int\/campaigns\/world-health-day\/2021\" target=\"_blank\" rel=\"noreferrer noopener\">Journ\u00e9e mondiale de la Sant\u00e9<\/a>, l\u2019Organisation mondiale de la Sant\u00e9 appelle \u00e0 l\u2019action afin d\u2019\u00e9liminer les in\u00e9galit\u00e9s en mati\u00e8re de sant\u00e9, et de veiller \u00e0 ce que toutes les personnes puissent acc\u00e9der \u00e0 des soins de qualit\u00e9 quand elles en ont besoin, l\u00e0 o\u00f9 elles sont.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">J\u2019ai moi-m\u00eame souffert des difficult\u00e9s d\u2019acc\u00e8s aux traitements et diagnostics m\u00e9dicaux et je suis fier aujourd\u2019hui de joindre ma voix \u00e0 celle de l\u2019OMS. Pendant mon enfance en Ouganda &#8211; un pays qui, selon les derniers chiffres du r\u00e9cent <a href=\"https:\/\/www.who.int\/publications\/i\/item\/9789240015791\" target=\"_blank\" rel=\"noreferrer noopener\">Rapport sur le paludisme dans le monde<\/a>, supporte l\u2019un des plus grands fardeaux dans le monde en raison du paludisme &#8211; j\u2019ai vu de mes propres yeux ce que signifie le paludisme. Je me souviens quand ma jumelle, qui souffrait d\u2019une forme persistante de la maladie, est tomb\u00e9e malade ; elle a \u00e9t\u00e9 forc\u00e9e de quitter l\u2019\u00e9cole pr\u00e9matur\u00e9ment et a failli mourir. \u00c0 l\u2019\u00e9poque, il y avait peu de centres de diagnostic et nous ne savions pas qu\u2019elle souffrait d\u2019une forme de paludisme r\u00e9sistant aux m\u00e9dicaments. Comme les mesures de pr\u00e9vention, p. ex. les moustiquaires, n\u2019\u00e9taient pas distribu\u00e9es partout, nous n\u2019en avions pas \u00e0 la maison.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Arriv\u00e9 au lyc\u00e9e, j\u2019ai contract\u00e9 la tuberculose. Il n\u2019\u00e9tait pas facile d\u2019avoir un diagnostic et un traitement pour la tuberculose l\u00e0 o\u00f9 je vivais, et j\u2019ai \u00e9t\u00e9 forc\u00e9 de manquer deux ans d\u2019\u00e9cole pour me faire soigner. Cela a pris plus de six mois pour obtenir un diagnostic, et j\u2019ai ensuite suivi un traitement prolong\u00e9 avec plusieurs s\u00e9jours \u00e0 l\u2019h\u00f4pital. C\u2019\u00e9tait un traitement cher et difficilement abordable pour ma famille.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ayant gu\u00e9ri de la tuberculose et \u00e9t\u00e9 t\u00e9moin des souffrances caus\u00e9es par d\u2019autres maladies \u00e9vitables, comme le paludisme, cela m\u2019a convaincu de faire des \u00e9tudes de m\u00e9decine. Je voulais sauver des vies, comme on avait sauv\u00e9 la mienne. Suite \u00e0 mon master \u00e0 la London School of Hygiene and Tropical Medicine, j\u2019ai ensuite obtenu un PhD en Zoologie \u00e0 l\u2019Universit\u00e9 de Makerere en Ouganda, \u00e0 l\u2019Universit\u00e9 de Yale aux \u00c9tats-Unis et \u00e0 l\u2019Universit\u00e9 de Pavia en Italie.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">J\u2019ai \u00e9galement particip\u00e9 aux campagnes de promotion comme celles du <a href=\"https:\/\/www.cdc.gov\/global-immunization\/stop\/\" target=\"_blank\" rel=\"noreferrer noopener\">CDC\/OMS STOP \u00e0 la Polio<\/a> et \u00e0 la Rougeole au Ghana et en \u00c9thiopie.<\/p>\n\n\n\n<div style=\"height:27px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/targetmalaria.org\/wp-content\/uploads\/2021\/04\/UGANDA_LAB_26-1-1024x683.jpg\" alt=\"\" class=\"wp-image-4935\" width=\"445\" height=\"297\" srcset=\"https:\/\/targetmalaria.org\/wp-content\/uploads\/2021\/04\/UGANDA_LAB_26-1-1024x683.jpg 1024w, https:\/\/targetmalaria.org\/wp-content\/uploads\/2021\/04\/UGANDA_LAB_26-1-300x200.jpg 300w, https:\/\/targetmalaria.org\/wp-content\/uploads\/2021\/04\/UGANDA_LAB_26-1-768x512.jpg 768w, https:\/\/targetmalaria.org\/wp-content\/uploads\/2021\/04\/UGANDA_LAB_26-1.jpg 1500w\" sizes=\"auto, (max-width: 445px) 100vw, 445px\" \/><figcaption><sub>Chercheurs au laboratoire de l&rsquo;Uganda Virus Research Institute (UVRI) d&rsquo;Entebbe, Uganda<\/sub><\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Je suis maintenant chercheur et Responsable pour l\u2019entomologie au projet <a href=\"https:\/\/targetmalaria.org\/fr\/where-we-operate\/uganda\/\">Target Malaria en Ouganda<\/a> \u00e0 l\u2019<a href=\"https:\/\/www.uvri.go.ug\/\" target=\"_blank\" rel=\"noreferrer noopener\">Uganda Virus Research Institute<\/a>. Par le biais de mon travail, j\u2019ai bien appris \u00e0 conna\u00eetre les vecteurs de maladie et les interactions h\u00f4te-pathog\u00e8ne. Mes \u00e9tudes m\u2019ont amen\u00e9 \u00e0 r\u00e9aliser l\u2019importance de la recherche de nouvelles m\u00e9thodes biologiques pour la lutte contre les maladies vectorielles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bien que l\u2019acc\u00e8s \u00e0 des services de sant\u00e9 efficaces se soit maintenant am\u00e9lior\u00e9 en Ouganda, o\u00f9 une <a href=\"https:\/\/www.health.go.ug\/project\/mosquito-net-distribution-campaign\/\" target=\"_blank\" rel=\"noreferrer noopener\">campagne nationale de distribution de moustiquaires<\/a> est en cours et une palette de m\u00e9dicaments antipaludiques efficaces est disponible gratuitement, il reste beaucoup de travail \u00e0 accomplir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019Ouganda repr\u00e9sente toujours 5&nbsp;% des cas de paludisme dans le monde et cette maladie reste la principale cause de d\u00e9c\u00e8s, surtout chez les enfants. Une approche efficace et concert\u00e9e pour vaincre le paludisme est n\u00e9cessaire.<\/p>\n\n\n\n<div style=\"height:27px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Outre des syst\u00e8mes de sant\u00e9 plus robustes et des investissements pour assurer un acc\u00e8s plus \u00e9quitable au diagnostic et au traitement du paludisme et la plus large adoption de moustiquaires et m\u00e9dicaments, le d\u00e9veloppement en parall\u00e8le de nouveaux outils de lutte anti-vectorielle, comme celui faisant l\u2019objet de la recherche Target Malaria, pourrait contribuer \u00e0 renforcer la lutte contre cette maladie mortelle.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En cette Journ\u00e9e mondiale de la Sant\u00e9, joignez-vous \u00e0 l\u2019appel en faveur d\u2019un monde meilleur, plus juste et plus sain. Une tr\u00e8s bonne Journ\u00e9e mondiale de la Sant\u00e9 \u00e0 tous ceux qui ont d\u00e9di\u00e9 leur vie et leur carri\u00e8re \u00e0 la lutte contre ces maladies faciles \u00e0 pr\u00e9venir !<\/p>\n\n\n\n<div style=\"height:49px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Le 7 avril, nous c\u00e9l\u00e9brons la Journ\u00e9e mondiale de la Sant\u00e9. Depuis 50 ans, cette journ\u00e9e a mis en lumi\u00e8re des questions importantes telles que la sant\u00e9 mentale, le r\u00f4le des infirmiers, infirmi\u00e8res et sages-femmes et l\u2019importance de la couverture sant\u00e9 universelle. Cette ann\u00e9e, la \u00ab&nbsp;Construction d\u2019un monde plus \u00e9quitable, plus sain&nbsp;\u00bb est le th\u00e8me [&hellip;]<\/p>\n","protected":false},"author":32,"featured_media":4931,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","featured_image_focal_point":[],"_image_focal_point":[],"footnotes":""},"categories":[88],"profile_tax":[],"class_list":["post-6949","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actus","post_writers-agapitus-kato","post_writers-agapitus-kato-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>C\u00e9l\u00e9bration de la Journ\u00e9e mondiale de la Sant\u00e9 - Target Malaria<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/targetmalaria.org\/fr\/latest\/actus\/celebration-de-la-journee-mondiale-de-la-sante\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00e9l\u00e9bration de la Journ\u00e9e mondiale de la Sant\u00e9 - Target Malaria\" \/>\n<meta property=\"og:description\" content=\"Le 7 avril, nous c\u00e9l\u00e9brons la Journ\u00e9e mondiale de la Sant\u00e9. Depuis 50 ans, cette journ\u00e9e a mis en lumi\u00e8re des questions importantes telles que la sant\u00e9 mentale, le r\u00f4le des infirmiers, infirmi\u00e8res et sages-femmes et l\u2019importance de la couverture sant\u00e9 universelle. Cette ann\u00e9e, la \u00ab&nbsp;Construction d\u2019un monde plus \u00e9quitable, plus sain&nbsp;\u00bb est le th\u00e8me [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/targetmalaria.org\/fr\/latest\/actus\/celebration-de-la-journee-mondiale-de-la-sante\/\" \/>\n<meta property=\"og:site_name\" content=\"Target Malaria\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TargetMalariaGlobal\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-07T09:20:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-29T07:36:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/targetmalaria.org\/wp-content\/uploads\/2021\/04\/Agapitus.png\" \/>\n\t<meta property=\"og:image:width\" content=\"764\" \/>\n\t<meta property=\"og:image:height\" content=\"764\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Yann Pablo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/targetmalaria.org\/wp-content\/uploads\/2021\/04\/UGANDA_LAB_26.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@TargetMalaria\" \/>\n<meta name=\"twitter:site\" content=\"@TargetMalaria\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Yann Pablo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/latest\\\/actus\\\/celebration-de-la-journee-mondiale-de-la-sante\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/latest\\\/actus\\\/celebration-de-la-journee-mondiale-de-la-sante\\\/\"},\"author\":{\"name\":\"Yann Pablo\",\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/#\\\/schema\\\/person\\\/c4715c8d1e550240ac403f56f435e8c8\"},\"headline\":\"C\u00e9l\u00e9bration de la Journ\u00e9e mondiale de la Sant\u00e9\",\"datePublished\":\"2021-04-07T09:20:00+00:00\",\"dateModified\":\"2025-08-29T07:36:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/latest\\\/actus\\\/celebration-de-la-journee-mondiale-de-la-sante\\\/\"},\"wordCount\":843,\"publisher\":{\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/latest\\\/actus\\\/celebration-de-la-journee-mondiale-de-la-sante\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/targetmalaria.org\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Agapitus.png\",\"articleSection\":[\"Actus\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/latest\\\/actus\\\/celebration-de-la-journee-mondiale-de-la-sante\\\/\",\"url\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/latest\\\/actus\\\/celebration-de-la-journee-mondiale-de-la-sante\\\/\",\"name\":\"C\u00e9l\u00e9bration de la Journ\u00e9e mondiale de la Sant\u00e9 - Target Malaria\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/latest\\\/actus\\\/celebration-de-la-journee-mondiale-de-la-sante\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/latest\\\/actus\\\/celebration-de-la-journee-mondiale-de-la-sante\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/targetmalaria.org\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Agapitus.png\",\"datePublished\":\"2021-04-07T09:20:00+00:00\",\"dateModified\":\"2025-08-29T07:36:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/latest\\\/actus\\\/celebration-de-la-journee-mondiale-de-la-sante\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/latest\\\/actus\\\/celebration-de-la-journee-mondiale-de-la-sante\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/latest\\\/actus\\\/celebration-de-la-journee-mondiale-de-la-sante\\\/#primaryimage\",\"url\":\"https:\\\/\\\/targetmalaria.org\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Agapitus.png\",\"contentUrl\":\"https:\\\/\\\/targetmalaria.org\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/Agapitus.png\",\"width\":764,\"height\":764},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/latest\\\/actus\\\/celebration-de-la-journee-mondiale-de-la-sante\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"C\u00e9l\u00e9bration de la Journ\u00e9e mondiale de la Sant\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/\",\"name\":\"Target Malaria\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/#organization\",\"name\":\"Target Malaria\",\"url\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/targetmalaria.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/target_malaria_bf_logo.png\",\"contentUrl\":\"https:\\\/\\\/targetmalaria.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/target_malaria_bf_logo.png\",\"width\":1920,\"height\":1080,\"caption\":\"Target Malaria\"},\"image\":{\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/TargetMalariaGlobal\\\/\",\"https:\\\/\\\/x.com\\\/TargetMalaria\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/target-malaria\",\"https:\\\/\\\/youtube.com\\\/@TargetMalaria\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/#\\\/schema\\\/person\\\/c4715c8d1e550240ac403f56f435e8c8\",\"name\":\"Yann Pablo\",\"sameAs\":[\"https:\\\/\\\/whybe.ch\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00e9l\u00e9bration de la Journ\u00e9e mondiale de la Sant\u00e9 - Target Malaria","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/targetmalaria.org\/fr\/latest\/actus\/celebration-de-la-journee-mondiale-de-la-sante\/","og_locale":"fr_FR","og_type":"article","og_title":"C\u00e9l\u00e9bration de la Journ\u00e9e mondiale de la Sant\u00e9 - Target Malaria","og_description":"Le 7 avril, nous c\u00e9l\u00e9brons la Journ\u00e9e mondiale de la Sant\u00e9. Depuis 50 ans, cette journ\u00e9e a mis en lumi\u00e8re des questions importantes telles que la sant\u00e9 mentale, le r\u00f4le des infirmiers, infirmi\u00e8res et sages-femmes et l\u2019importance de la couverture sant\u00e9 universelle. Cette ann\u00e9e, la \u00ab&nbsp;Construction d\u2019un monde plus \u00e9quitable, plus sain&nbsp;\u00bb est le th\u00e8me [&hellip;]","og_url":"https:\/\/targetmalaria.org\/fr\/latest\/actus\/celebration-de-la-journee-mondiale-de-la-sante\/","og_site_name":"Target Malaria","article_publisher":"https:\/\/www.facebook.com\/TargetMalariaGlobal\/","article_published_time":"2021-04-07T09:20:00+00:00","article_modified_time":"2025-08-29T07:36:45+00:00","og_image":[{"width":764,"height":764,"url":"https:\/\/targetmalaria.org\/wp-content\/uploads\/2021\/04\/Agapitus.png","type":"image\/png"}],"author":"Yann Pablo","twitter_card":"summary_large_image","twitter_image":"https:\/\/targetmalaria.org\/wp-content\/uploads\/2021\/04\/UGANDA_LAB_26.jpg","twitter_creator":"@TargetMalaria","twitter_site":"@TargetMalaria","twitter_misc":{"\u00c9crit par":"Yann Pablo","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/targetmalaria.org\/fr\/latest\/actus\/celebration-de-la-journee-mondiale-de-la-sante\/#article","isPartOf":{"@id":"https:\/\/targetmalaria.org\/fr\/latest\/actus\/celebration-de-la-journee-mondiale-de-la-sante\/"},"author":{"name":"Yann Pablo","@id":"https:\/\/targetmalaria.org\/fr\/#\/schema\/person\/c4715c8d1e550240ac403f56f435e8c8"},"headline":"C\u00e9l\u00e9bration de la Journ\u00e9e mondiale de la Sant\u00e9","datePublished":"2021-04-07T09:20:00+00:00","dateModified":"2025-08-29T07:36:45+00:00","mainEntityOfPage":{"@id":"https:\/\/targetmalaria.org\/fr\/latest\/actus\/celebration-de-la-journee-mondiale-de-la-sante\/"},"wordCount":843,"publisher":{"@id":"https:\/\/targetmalaria.org\/fr\/#organization"},"image":{"@id":"https:\/\/targetmalaria.org\/fr\/latest\/actus\/celebration-de-la-journee-mondiale-de-la-sante\/#primaryimage"},"thumbnailUrl":"https:\/\/targetmalaria.org\/wp-content\/uploads\/2021\/04\/Agapitus.png","articleSection":["Actus"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/targetmalaria.org\/fr\/latest\/actus\/celebration-de-la-journee-mondiale-de-la-sante\/","url":"https:\/\/targetmalaria.org\/fr\/latest\/actus\/celebration-de-la-journee-mondiale-de-la-sante\/","name":"C\u00e9l\u00e9bration de la Journ\u00e9e mondiale de la Sant\u00e9 - Target Malaria","isPartOf":{"@id":"https:\/\/targetmalaria.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/targetmalaria.org\/fr\/latest\/actus\/celebration-de-la-journee-mondiale-de-la-sante\/#primaryimage"},"image":{"@id":"https:\/\/targetmalaria.org\/fr\/latest\/actus\/celebration-de-la-journee-mondiale-de-la-sante\/#primaryimage"},"thumbnailUrl":"https:\/\/targetmalaria.org\/wp-content\/uploads\/2021\/04\/Agapitus.png","datePublished":"2021-04-07T09:20:00+00:00","dateModified":"2025-08-29T07:36:45+00:00","breadcrumb":{"@id":"https:\/\/targetmalaria.org\/fr\/latest\/actus\/celebration-de-la-journee-mondiale-de-la-sante\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/targetmalaria.org\/fr\/latest\/actus\/celebration-de-la-journee-mondiale-de-la-sante\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/targetmalaria.org\/fr\/latest\/actus\/celebration-de-la-journee-mondiale-de-la-sante\/#primaryimage","url":"https:\/\/targetmalaria.org\/wp-content\/uploads\/2021\/04\/Agapitus.png","contentUrl":"https:\/\/targetmalaria.org\/wp-content\/uploads\/2021\/04\/Agapitus.png","width":764,"height":764},{"@type":"BreadcrumbList","@id":"https:\/\/targetmalaria.org\/fr\/latest\/actus\/celebration-de-la-journee-mondiale-de-la-sante\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/targetmalaria.org\/fr\/"},{"@type":"ListItem","position":2,"name":"C\u00e9l\u00e9bration de la Journ\u00e9e mondiale de la Sant\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/targetmalaria.org\/fr\/#website","url":"https:\/\/targetmalaria.org\/fr\/","name":"Target Malaria","description":"","publisher":{"@id":"https:\/\/targetmalaria.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/targetmalaria.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/targetmalaria.org\/fr\/#organization","name":"Target Malaria","url":"https:\/\/targetmalaria.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/targetmalaria.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/targetmalaria.org\/wp-content\/uploads\/2025\/08\/target_malaria_bf_logo.png","contentUrl":"https:\/\/targetmalaria.org\/wp-content\/uploads\/2025\/08\/target_malaria_bf_logo.png","width":1920,"height":1080,"caption":"Target Malaria"},"image":{"@id":"https:\/\/targetmalaria.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/TargetMalariaGlobal\/","https:\/\/x.com\/TargetMalaria","https:\/\/www.linkedin.com\/company\/target-malaria","https:\/\/youtube.com\/@TargetMalaria"]},{"@type":"Person","@id":"https:\/\/targetmalaria.org\/fr\/#\/schema\/person\/c4715c8d1e550240ac403f56f435e8c8","name":"Yann Pablo","sameAs":["https:\/\/whybe.ch"]}]}},"_links":{"self":[{"href":"https:\/\/targetmalaria.org\/fr\/wp-json\/wp\/v2\/posts\/6949","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/targetmalaria.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/targetmalaria.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/targetmalaria.org\/fr\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/targetmalaria.org\/fr\/wp-json\/wp\/v2\/comments?post=6949"}],"version-history":[{"count":1,"href":"https:\/\/targetmalaria.org\/fr\/wp-json\/wp\/v2\/posts\/6949\/revisions"}],"predecessor-version":[{"id":22393,"href":"https:\/\/targetmalaria.org\/fr\/wp-json\/wp\/v2\/posts\/6949\/revisions\/22393"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/targetmalaria.org\/fr\/wp-json\/wp\/v2\/media\/4931"}],"wp:attachment":[{"href":"https:\/\/targetmalaria.org\/fr\/wp-json\/wp\/v2\/media?parent=6949"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/targetmalaria.org\/fr\/wp-json\/wp\/v2\/categories?post=6949"},{"taxonomy":"profile_tax","embeddable":true,"href":"https:\/\/targetmalaria.org\/fr\/wp-json\/wp\/v2\/profile_tax?post=6949"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}