{"id":23015,"date":"2025-10-16T10:42:05","date_gmt":"2025-10-16T09:42:05","guid":{"rendered":"https:\/\/targetmalaria.org\/?p=23015"},"modified":"2025-10-16T11:26:31","modified_gmt":"2025-10-16T10:26:31","slug":"iucn-agrees-first-global-policy-on-synthetic-biology","status":"publish","type":"post","link":"https:\/\/targetmalaria.org\/fr\/latest\/actus\/iucn-agrees-first-global-policy-on-synthetic-biology\/","title":{"rendered":"L&rsquo;UICN adopte la premi\u00e8re politique mondiale sur la biologie synth\u00e9tique"},"content":{"rendered":"<figure style=\"aspect-ratio:21\/9\" class=\"wp-block-post-featured-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1110\" height=\"834\" src=\"https:\/\/targetmalaria.org\/wp-content\/uploads\/2025\/10\/121025_am_016.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"IUCN World Conservation Congress 2025.\nGeneral views.\n\nPhoto\u00a9IUCN\/Andrew McConnell\/Workers Photos\" style=\"width:100%;height:100%;object-fit:cover;\" srcset=\"https:\/\/targetmalaria.org\/wp-content\/uploads\/2025\/10\/121025_am_016.jpg 1110w, https:\/\/targetmalaria.org\/wp-content\/uploads\/2025\/10\/121025_am_016-425x319.jpg 425w, https:\/\/targetmalaria.org\/wp-content\/uploads\/2025\/10\/121025_am_016-1024x769.jpg 1024w, https:\/\/targetmalaria.org\/wp-content\/uploads\/2025\/10\/121025_am_016-768x577.jpg 768w\" sizes=\"auto, (max-width: 1110px) 100vw, 1110px\" \/><\/figure>\n\n<div class=\"post_date\">Post\u00e9 le 16 octobre 2025<\/div><div class=\"post_details\"><figure class=\"post_author\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/targetmalaria.org\/wp-content\/uploads\/2025\/10\/IUCN_logo.svg_-150x150.png\" class=\"attachment-thumbnail size-thumbnail\" alt=\"IUCN Logo\" \/><\/figure><div class=author_info><h6>Par International Union for Conservation of Nature (IUCN)<\/h6><\/div><\/div>\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-79fb870f wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:75%\">\n<h3 class=\"wp-block-heading\" style=\"padding-top:0\">L&rsquo;UICN a adopt\u00e9 la toute premi\u00e8re politique mondiale sur la biologie synth\u00e9tique et la conservation de la nature.\u00a0<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Cette politique a \u00e9t\u00e9 adopt\u00e9e par l&rsquo;organe d\u00e9cisionnel supr\u00eame de l&rsquo;UICN, son Assembl\u00e9e des membres, qui regroupe les organisations gouvernementales, non gouvernementales et autochtones de l&rsquo;Union, lors du Congr\u00e8s mondial de la nature de l&rsquo;UICN \u00e0 Abu Dhabi.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Elle couvre la biologie synth\u00e9tique en relation avec la conservation de la nature, qu&rsquo;elle soit appliqu\u00e9e \u00e0 des fins de conservation ou dans d&rsquo;autres secteurs tels que l&rsquo;industrie, l&rsquo;agriculture ou la m\u00e9decine, avec des impacts directs ou indirects potentiels sur la nature.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u00ab La technologie de la biologie synth\u00e9tique progresse, et ses implications potentielles pour la conservation de la nature s&rsquo;accroissent \u00bb, <\/em>a d\u00e9clar\u00e9 <strong>Thomas Brooks, scientifique en chef de l&rsquo;UICN<\/strong>. <em>\u00ab Cette politique garantit que l&rsquo;UICN est pr\u00eate, en fournissant un cadre directeur fa\u00e7onn\u00e9 par les perspectives de nos membres gr\u00e2ce au processus de consultation le plus inclusif et participatif jamais entrepris au sein de l&rsquo;UICN, soulignant le r\u00f4le de notre Union dans la convocation et l&rsquo;orientation des d\u00e9cisions difficiles. \u00bb<\/em>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9tant donn\u00e9 que la biologie synth\u00e9tique peut pr\u00e9senter \u00e0 la fois des avantages substantiels (par exemple, pour restaurer la diversit\u00e9 g\u00e9n\u00e9tique perdue ou \u00e9radiquer localement les esp\u00e8ces exotiques envahissantes) et des risques importants (par exemple, des cascades \u00e9cologiques involontaires), la position \u00e9quilibr\u00e9e de la politique est importante : elle permet l&rsquo;innovation mais insiste sur la vigilance. Les applications de la biologie synth\u00e9tique ayant des implications pour tous les secteurs de la soci\u00e9t\u00e9, en particulier pour les peuples autochtones et les communaut\u00e9s locales, la politique \u00e9nonce clairement les consid\u00e9rations \u00e0 prendre en compte pour garantir leur participation \u00e0 la planification et \u00e0 la prise de d\u00e9cision, notamment par le biais du principe du consentement libre, pr\u00e9alable et \u00e9clair\u00e9.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u00ab Cette nouvelle politique de l&rsquo;UICN est importante pour trois raisons \u00bb, <\/em><strong>a d\u00e9clar\u00e9 Maria Julia Oliva, copr\u00e9sidente du groupe de travail sur l&rsquo;\u00e9laboration des politiques, membre de la Commission mondiale du droit de l&rsquo;environnement de l&rsquo;UICN et directrice des politiques et de la transformation sectorielle au sein de l&rsquo;Union of Ethical BioTrade.<\/strong> <em>\u00ab Elle donne un nouvel espoir pour sauver les nombreuses esp\u00e8ces menac\u00e9es qui font face \u00e0 des menaces encore ing\u00e9rables. Elle garantit que les utilisations de la biologie synth\u00e9tique \u00e0 des fins de conservation se d\u00e9roulent selon une approche pr\u00e9ventive, et elle exige que d&rsquo;autres secteurs int\u00e8grent les pr\u00e9occupations li\u00e9es \u00e0 la conservation de la nature dans leurs applications de la biologie synth\u00e9tique. \u00bb<\/em>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ce sujet fait depuis longtemps l&rsquo;objet de d\u00e9bats, une petite partie de la communaut\u00e9 des d\u00e9fenseurs de l&rsquo;environnement \u00e9tant favorable \u00e0 l&rsquo;application de la biologie synth\u00e9tique \u00e0 la conservation de la nature, une autre petite partie s&rsquo;y opposant, et la plupart des d\u00e9fenseurs de l&rsquo;environnement restant jusqu&rsquo;\u00e0 pr\u00e9sent incertains ou ind\u00e9cis sur la question. Cette politique \u00e9quilibr\u00e9e refl\u00e8te la position unique de l&rsquo;UICN, qui consiste \u00e0 trouver un terrain d&rsquo;entente sur des questions polaris\u00e9es en r\u00e9unissant les membres de l&rsquo;Union et ses commissions d&rsquo;experts ind\u00e9pendants.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u00ab Un \u00e9l\u00e9ment crucial qui a contribu\u00e9 \u00e0 l&rsquo;\u00e9laboration de cette politique a \u00e9t\u00e9 la convocation par l&rsquo;UICN de sa toute premi\u00e8re Assembl\u00e9e des citoyens, un m\u00e9canisme innovant permettant d&rsquo;entendre les opinions d&rsquo;un \u00e9chantillon diversifi\u00e9 de membres de l&rsquo;UICN. L&rsquo;Assembl\u00e9e des citoyens \u00e9tait compos\u00e9e de repr\u00e9sentants de 15 membres de l&rsquo;UICN, r\u00e9partis de mani\u00e8re \u00e9quilibr\u00e9e entre les huit r\u00e9gions statutaires de l&rsquo;UICN, les gouvernements et la soci\u00e9t\u00e9 civile, et les deux sexes \u00bb,<\/em><strong>a d\u00e9clar\u00e9 Bibiana Sucre, conseill\u00e8re de l&rsquo;UICN et directrice ex\u00e9cutive de Provita, membre v\u00e9n\u00e9zu\u00e9lien de l&rsquo;UICN<\/strong>. <em>\u00ab Les participants \u00e0 l&rsquo;Assembl\u00e9e citoyenne ont suivi une formation intensive, puis ont pass\u00e9 une semaine \u00e0 d\u00e9lib\u00e9rer afin de formuler 80 recommandations concises pour la politique de l&rsquo;UICN. \u00bb<\/em>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les commentaires de l&rsquo;ensemble de l&rsquo;UICN sur ces recommandations, ainsi que des webinaires, la sollicitation de contributions de l&rsquo;ensemble des membres et des consultations cibl\u00e9es avec les forums r\u00e9gionaux de conservation, les comit\u00e9s, les commissions et les organisations de peuples autochtones membres de l&rsquo;UICN, ont servi de base \u00e0 l&rsquo;\u00e9laboration de la politique. Elle a \u00e9t\u00e9 r\u00e9dig\u00e9e par un groupe de travail sur l&rsquo;\u00e9laboration des politiques largement repr\u00e9sentatif, nomm\u00e9 par Son Excellence Razan Al Mubarak, pr\u00e9sidente de l&rsquo;UICN, et a fait l&rsquo;objet de deux cycles d&rsquo;examen par les pairs de l&rsquo;ensemble de l&rsquo;Union, recevant plus de 800 commentaires. La Convention sur la diversit\u00e9 biologique a particip\u00e9 \u00e0 ce processus en tant qu&rsquo;observateur.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cette politique ne doit pas \u00eatre interpr\u00e9t\u00e9e comme un soutien ou une opposition \u00e0 la biologie synth\u00e9tique. Elle n&rsquo;a pas pour but de remplacer les efforts actuels et futurs visant \u00e0 lutter contre la perte de biodiversit\u00e9. Elle pourrait toutefois les compl\u00e9ter. Elle fournit surtout un cadre pour la prise de d\u00e9cision au cas par cas, en \u00e9tablissant un m\u00e9canisme qui guide la mani\u00e8re, le moment et les conditions dans lesquels les applications de la biologie synth\u00e9tique pourraient \u00eatre approuv\u00e9es et introduites.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u00ab La nouvelle politique de l&rsquo;UICN encourage la mise en place de capacit\u00e9s accessibles en mati\u00e8re de biologie synth\u00e9tique et de conservation de la nature \u00bb,<\/em> <strong>a d\u00e9clar\u00e9 le professeur Zabta Shinwari, copr\u00e9sident du groupe de travail sur l&rsquo;\u00e9laboration des politiques, membre de la Commission de survie des esp\u00e8ces de l&rsquo;UICN et vice-chancelier de l&rsquo;Universit\u00e9 f\u00e9d\u00e9rale d&rsquo;arts, de sciences et de technologie de l&rsquo;ourdou. <\/strong><em>\u00ab Cela devrait inclure une formation et une expertise technique pour soutenir l&rsquo;engagement, la compr\u00e9hension, l&rsquo;\u00e9laboration des politiques, la mise en \u0153uvre, le suivi et les \u00e9valuations d&rsquo;impact. \u00bb<\/em>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Avec l&rsquo;adoption de cette politique, l&rsquo;UICN invite tous ses membres \u00e0 la suivre, ainsi que les parties \u00e0 la Convention sur la diversit\u00e9 biologique, \u00e0 la Convention sur le commerce international des esp\u00e8ces menac\u00e9es d&rsquo;extinction et \u00e0 d&rsquo;autres accords multilat\u00e9raux sur l&rsquo;environnement \u00e0 en tenir compte lorsqu&rsquo;elles examinent la question de la biologie synth\u00e9tique et de la conservation de la nature. La politique suit la d\u00e9finition de la biologie synth\u00e9tique adopt\u00e9e par la Convention sur la diversit\u00e9 biologique, \u00e0 savoir : \u00ab Un d\u00e9veloppement plus pouss\u00e9 et une nouvelle dimension de la biotechnologie moderne qui combine la science, la technologie et l&rsquo;ing\u00e9nierie pour faciliter et acc\u00e9l\u00e9rer la compr\u00e9hension, la conception, la reconception, la fabrication et\/ou la modification de mat\u00e9riel g\u00e9n\u00e9tique, d&rsquo;organismes vivants et de syst\u00e8mes biologiques. \u00bb&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le d\u00e9veloppement de la politique de l&rsquo;UICN sur la biologie synth\u00e9tique et la conservation de la nature a b\u00e9n\u00e9fici\u00e9 d&rsquo;un financement g\u00e9n\u00e9reux de la part du minist\u00e8re f\u00e9d\u00e9ral allemand de l&rsquo;Environnement, de la Protection de la nature, de la S\u00fbret\u00e9 nucl\u00e9aire et de la Protection des consommateurs, ainsi que de la Fondation Gordon et Betty Moore.&nbsp;<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;UICN a adopt\u00e9 la toute premi\u00e8re politique mondiale sur la biologie synth\u00e9tique et la conservation de la nature.\u00a0 Cette politique a \u00e9t\u00e9 adopt\u00e9e par l&rsquo;organe d\u00e9cisionnel supr\u00eame de l&rsquo;UICN, son Assembl\u00e9e des membres, qui regroupe les organisations gouvernementales, non gouvernementales et autochtones de l&rsquo;Union, lors du Congr\u00e8s mondial de la nature de l&rsquo;UICN \u00e0 Abu [&hellip;]<\/p>\n","protected":false},"author":31,"featured_media":23020,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","featured_image_focal_point":[],"_image_focal_point":[],"footnotes":""},"categories":[88],"profile_tax":[],"class_list":["post-23015","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actus","post_writers-international-union-for-conservation-of-nature-iucn-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;UICN adopte la premi\u00e8re politique mondiale sur la biologie synth\u00e9tique - Target Malaria<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/targetmalaria.org\/fr\/latest\/actus\/iucn-agrees-first-global-policy-on-synthetic-biology\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;UICN adopte la premi\u00e8re politique mondiale sur la biologie synth\u00e9tique - Target Malaria\" \/>\n<meta property=\"og:description\" content=\"L&rsquo;UICN a adopt\u00e9 la toute premi\u00e8re politique mondiale sur la biologie synth\u00e9tique et la conservation de la nature.\u00a0 Cette politique a \u00e9t\u00e9 adopt\u00e9e par l&rsquo;organe d\u00e9cisionnel supr\u00eame de l&rsquo;UICN, son Assembl\u00e9e des membres, qui regroupe les organisations gouvernementales, non gouvernementales et autochtones de l&rsquo;Union, lors du Congr\u00e8s mondial de la nature de l&rsquo;UICN \u00e0 Abu [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/targetmalaria.org\/fr\/latest\/actus\/iucn-agrees-first-global-policy-on-synthetic-biology\/\" \/>\n<meta property=\"og:site_name\" content=\"Target Malaria\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/TargetMalariaGlobal\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-16T09:42:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-16T10:26:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/targetmalaria.org\/wp-content\/uploads\/2025\/10\/121025_am_016.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1110\" \/>\n\t<meta property=\"og:image:height\" content=\"834\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Lorraine Gibson\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@TargetMalaria\" \/>\n<meta name=\"twitter:site\" content=\"@TargetMalaria\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Lorraine Gibson\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/latest\\\/actus\\\/iucn-agrees-first-global-policy-on-synthetic-biology\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/latest\\\/actus\\\/iucn-agrees-first-global-policy-on-synthetic-biology\\\/\"},\"author\":{\"name\":\"Lorraine Gibson\",\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/#\\\/schema\\\/person\\\/492d9f8e39a2bb31b5ac1b64b7581bb0\"},\"headline\":\"L&rsquo;UICN adopte la premi\u00e8re politique mondiale sur la biologie synth\u00e9tique\",\"datePublished\":\"2025-10-16T09:42:05+00:00\",\"dateModified\":\"2025-10-16T10:26:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/latest\\\/actus\\\/iucn-agrees-first-global-policy-on-synthetic-biology\\\/\"},\"wordCount\":1265,\"publisher\":{\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/latest\\\/actus\\\/iucn-agrees-first-global-policy-on-synthetic-biology\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/targetmalaria.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/121025_am_016.jpg\",\"articleSection\":[\"Actus\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/latest\\\/actus\\\/iucn-agrees-first-global-policy-on-synthetic-biology\\\/\",\"url\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/latest\\\/actus\\\/iucn-agrees-first-global-policy-on-synthetic-biology\\\/\",\"name\":\"L'UICN adopte la premi\u00e8re politique mondiale sur la biologie synth\u00e9tique - Target Malaria\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/latest\\\/actus\\\/iucn-agrees-first-global-policy-on-synthetic-biology\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/latest\\\/actus\\\/iucn-agrees-first-global-policy-on-synthetic-biology\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/targetmalaria.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/121025_am_016.jpg\",\"datePublished\":\"2025-10-16T09:42:05+00:00\",\"dateModified\":\"2025-10-16T10:26:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/latest\\\/actus\\\/iucn-agrees-first-global-policy-on-synthetic-biology\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/latest\\\/actus\\\/iucn-agrees-first-global-policy-on-synthetic-biology\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/latest\\\/actus\\\/iucn-agrees-first-global-policy-on-synthetic-biology\\\/#primaryimage\",\"url\":\"https:\\\/\\\/targetmalaria.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/121025_am_016.jpg\",\"contentUrl\":\"https:\\\/\\\/targetmalaria.org\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/121025_am_016.jpg\",\"width\":1110,\"height\":834,\"caption\":\"IUCN World Conservation Congress 2025. General views. Photo\u00a9IUCN\\\/Andrew McConnell\\\/Workers Photos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/latest\\\/actus\\\/iucn-agrees-first-global-policy-on-synthetic-biology\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&#8217;UICN adopte la premi\u00e8re politique mondiale sur la biologie synth\u00e9tique\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/\",\"name\":\"Target Malaria\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/#organization\",\"name\":\"Target Malaria\",\"url\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/targetmalaria.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/target_malaria_bf_logo.png\",\"contentUrl\":\"https:\\\/\\\/targetmalaria.org\\\/wp-content\\\/uploads\\\/2025\\\/08\\\/target_malaria_bf_logo.png\",\"width\":1920,\"height\":1080,\"caption\":\"Target Malaria\"},\"image\":{\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/TargetMalariaGlobal\\\/\",\"https:\\\/\\\/x.com\\\/TargetMalaria\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/target-malaria\",\"https:\\\/\\\/youtube.com\\\/@TargetMalaria\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/targetmalaria.org\\\/fr\\\/#\\\/schema\\\/person\\\/492d9f8e39a2bb31b5ac1b64b7581bb0\",\"name\":\"Lorraine Gibson\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'UICN adopte la premi\u00e8re politique mondiale sur la biologie synth\u00e9tique - Target Malaria","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/targetmalaria.org\/fr\/latest\/actus\/iucn-agrees-first-global-policy-on-synthetic-biology\/","og_locale":"fr_FR","og_type":"article","og_title":"L'UICN adopte la premi\u00e8re politique mondiale sur la biologie synth\u00e9tique - Target Malaria","og_description":"L&rsquo;UICN a adopt\u00e9 la toute premi\u00e8re politique mondiale sur la biologie synth\u00e9tique et la conservation de la nature.\u00a0 Cette politique a \u00e9t\u00e9 adopt\u00e9e par l&rsquo;organe d\u00e9cisionnel supr\u00eame de l&rsquo;UICN, son Assembl\u00e9e des membres, qui regroupe les organisations gouvernementales, non gouvernementales et autochtones de l&rsquo;Union, lors du Congr\u00e8s mondial de la nature de l&rsquo;UICN \u00e0 Abu [&hellip;]","og_url":"https:\/\/targetmalaria.org\/fr\/latest\/actus\/iucn-agrees-first-global-policy-on-synthetic-biology\/","og_site_name":"Target Malaria","article_publisher":"https:\/\/www.facebook.com\/TargetMalariaGlobal\/","article_published_time":"2025-10-16T09:42:05+00:00","article_modified_time":"2025-10-16T10:26:31+00:00","og_image":[{"width":1110,"height":834,"url":"https:\/\/targetmalaria.org\/wp-content\/uploads\/2025\/10\/121025_am_016.jpg","type":"image\/jpeg"}],"author":"Lorraine Gibson","twitter_card":"summary_large_image","twitter_creator":"@TargetMalaria","twitter_site":"@TargetMalaria","twitter_misc":{"\u00c9crit par":"Lorraine Gibson","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/targetmalaria.org\/fr\/latest\/actus\/iucn-agrees-first-global-policy-on-synthetic-biology\/#article","isPartOf":{"@id":"https:\/\/targetmalaria.org\/fr\/latest\/actus\/iucn-agrees-first-global-policy-on-synthetic-biology\/"},"author":{"name":"Lorraine Gibson","@id":"https:\/\/targetmalaria.org\/fr\/#\/schema\/person\/492d9f8e39a2bb31b5ac1b64b7581bb0"},"headline":"L&rsquo;UICN adopte la premi\u00e8re politique mondiale sur la biologie synth\u00e9tique","datePublished":"2025-10-16T09:42:05+00:00","dateModified":"2025-10-16T10:26:31+00:00","mainEntityOfPage":{"@id":"https:\/\/targetmalaria.org\/fr\/latest\/actus\/iucn-agrees-first-global-policy-on-synthetic-biology\/"},"wordCount":1265,"publisher":{"@id":"https:\/\/targetmalaria.org\/fr\/#organization"},"image":{"@id":"https:\/\/targetmalaria.org\/fr\/latest\/actus\/iucn-agrees-first-global-policy-on-synthetic-biology\/#primaryimage"},"thumbnailUrl":"https:\/\/targetmalaria.org\/wp-content\/uploads\/2025\/10\/121025_am_016.jpg","articleSection":["Actus"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/targetmalaria.org\/fr\/latest\/actus\/iucn-agrees-first-global-policy-on-synthetic-biology\/","url":"https:\/\/targetmalaria.org\/fr\/latest\/actus\/iucn-agrees-first-global-policy-on-synthetic-biology\/","name":"L'UICN adopte la premi\u00e8re politique mondiale sur la biologie synth\u00e9tique - Target Malaria","isPartOf":{"@id":"https:\/\/targetmalaria.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/targetmalaria.org\/fr\/latest\/actus\/iucn-agrees-first-global-policy-on-synthetic-biology\/#primaryimage"},"image":{"@id":"https:\/\/targetmalaria.org\/fr\/latest\/actus\/iucn-agrees-first-global-policy-on-synthetic-biology\/#primaryimage"},"thumbnailUrl":"https:\/\/targetmalaria.org\/wp-content\/uploads\/2025\/10\/121025_am_016.jpg","datePublished":"2025-10-16T09:42:05+00:00","dateModified":"2025-10-16T10:26:31+00:00","breadcrumb":{"@id":"https:\/\/targetmalaria.org\/fr\/latest\/actus\/iucn-agrees-first-global-policy-on-synthetic-biology\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/targetmalaria.org\/fr\/latest\/actus\/iucn-agrees-first-global-policy-on-synthetic-biology\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/targetmalaria.org\/fr\/latest\/actus\/iucn-agrees-first-global-policy-on-synthetic-biology\/#primaryimage","url":"https:\/\/targetmalaria.org\/wp-content\/uploads\/2025\/10\/121025_am_016.jpg","contentUrl":"https:\/\/targetmalaria.org\/wp-content\/uploads\/2025\/10\/121025_am_016.jpg","width":1110,"height":834,"caption":"IUCN World Conservation Congress 2025. General views. Photo\u00a9IUCN\/Andrew McConnell\/Workers Photos"},{"@type":"BreadcrumbList","@id":"https:\/\/targetmalaria.org\/fr\/latest\/actus\/iucn-agrees-first-global-policy-on-synthetic-biology\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/targetmalaria.org\/fr\/"},{"@type":"ListItem","position":2,"name":"L&#8217;UICN adopte la premi\u00e8re politique mondiale sur la biologie synth\u00e9tique"}]},{"@type":"WebSite","@id":"https:\/\/targetmalaria.org\/fr\/#website","url":"https:\/\/targetmalaria.org\/fr\/","name":"Target Malaria","description":"","publisher":{"@id":"https:\/\/targetmalaria.org\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/targetmalaria.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/targetmalaria.org\/fr\/#organization","name":"Target Malaria","url":"https:\/\/targetmalaria.org\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/targetmalaria.org\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/targetmalaria.org\/wp-content\/uploads\/2025\/08\/target_malaria_bf_logo.png","contentUrl":"https:\/\/targetmalaria.org\/wp-content\/uploads\/2025\/08\/target_malaria_bf_logo.png","width":1920,"height":1080,"caption":"Target Malaria"},"image":{"@id":"https:\/\/targetmalaria.org\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/TargetMalariaGlobal\/","https:\/\/x.com\/TargetMalaria","https:\/\/www.linkedin.com\/company\/target-malaria","https:\/\/youtube.com\/@TargetMalaria"]},{"@type":"Person","@id":"https:\/\/targetmalaria.org\/fr\/#\/schema\/person\/492d9f8e39a2bb31b5ac1b64b7581bb0","name":"Lorraine Gibson"}]}},"_links":{"self":[{"href":"https:\/\/targetmalaria.org\/fr\/wp-json\/wp\/v2\/posts\/23015","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/targetmalaria.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/targetmalaria.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/targetmalaria.org\/fr\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/targetmalaria.org\/fr\/wp-json\/wp\/v2\/comments?post=23015"}],"version-history":[{"count":4,"href":"https:\/\/targetmalaria.org\/fr\/wp-json\/wp\/v2\/posts\/23015\/revisions"}],"predecessor-version":[{"id":23049,"href":"https:\/\/targetmalaria.org\/fr\/wp-json\/wp\/v2\/posts\/23015\/revisions\/23049"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/targetmalaria.org\/fr\/wp-json\/wp\/v2\/media\/23020"}],"wp:attachment":[{"href":"https:\/\/targetmalaria.org\/fr\/wp-json\/wp\/v2\/media?parent=23015"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/targetmalaria.org\/fr\/wp-json\/wp\/v2\/categories?post=23015"},{"taxonomy":"profile_tax","embeddable":true,"href":"https:\/\/targetmalaria.org\/fr\/wp-json\/wp\/v2\/profile_tax?post=23015"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}